{"id":9,"count":3,"description":"Cambia el revestimiento de suelos y paredes y consigue una casa de dise\u00f1o. \u00bfTe gusta el estilo r\u00fastico, el minimalista, el vintage o cualquier otro? Descubre los mejores consejos para crear un ambiente propio en tu hogar.\r\n\r\nSuelos de imitaci\u00f3n a madera combinados con piedra y muebles robustos o suelos de acabado fino con paredes en tonos claros y mobiliario en tonos pastel, las combinaciones son infinitas. Solo se trata de encontrar la tuya. Dale un toque diferente a las habitaciones, al ba\u00f1o o a tu cocina. Realiza tu reforma con nuestros consejos. En Chafiras recogemos las \u00faltimas tendencias y te mostramos las mejores ideas para la modernizaci\u00f3n de tu casa.","link":"https:\/\/chafiras.com\/inspiracion\/sobre\/decoracion\/ceramica\/","name":"Cer\u00e1mica","slug":"ceramica","taxonomy":"category","parent":1,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ideas para revestimiento de suelos y paredes: losas, azulejos,...<\/title>\n<meta name=\"description\" content=\"\u00bfC\u00f3mo elegir suelos o azulejos para la pared del hogar? Consejos, ideas, estilos, tendencias,\u2026 Cambia el revestimiento del piso y las paredes \u00a1tu sue\u00f1o aqu\u00ed!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/chafiras.com\/inspiracion\/sobre\/decoracion\/ceramica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ideas para revestimiento de suelos y paredes: losas, azulejos,...\" \/>\n<meta property=\"og:description\" content=\"\u00bfC\u00f3mo elegir suelos o azulejos para la pared del hogar? Consejos, ideas, estilos, tendencias,\u2026 Cambia el revestimiento del piso y las paredes \u00a1tu sue\u00f1o aqu\u00ed!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/chafiras.com\/inspiracion\/sobre\/decoracion\/ceramica\/\" \/>\n<meta property=\"og:site_name\" content=\"Inspiraci\u00f3n para llevarte nuestra experiencia a casa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/chafiras.com\/inspiracion\/sobre\/decoracion\/ceramica\/\",\"url\":\"https:\/\/chafiras.com\/inspiracion\/sobre\/decoracion\/ceramica\/\",\"name\":\"Ideas para revestimiento de suelos y paredes: losas, azulejos,...\",\"isPartOf\":{\"@id\":\"https:\/\/chafiras.com\/inspiracion\/#website\"},\"description\":\"\u00bfC\u00f3mo elegir suelos o azulejos para la pared del hogar? Consejos, ideas, estilos, tendencias,\u2026 Cambia el revestimiento del piso y las paredes \u00a1tu sue\u00f1o aqu\u00ed!\",\"breadcrumb\":{\"@id\":\"https:\/\/chafiras.com\/inspiracion\/sobre\/decoracion\/ceramica\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/chafiras.com\/inspiracion\/sobre\/decoracion\/ceramica\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Chafiras\",\"item\":\"https:\/\/chafiras.com\/inspiracion\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Decoraci\u00f3n\",\"item\":\"https:\/\/chafiras.com\/inspiracion\/sobre\/decoracion\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cer\u00e1mica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/chafiras.com\/inspiracion\/#website\",\"url\":\"https:\/\/chafiras.com\/inspiracion\/\",\"name\":\"Inspiraci\u00f3n para llevarte nuestra experiencia a casa\",\"description\":\"Herramientas para tu d\u00eda a d\u00eda\",\"publisher\":{\"@id\":\"https:\/\/chafiras.com\/inspiracion\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/chafiras.com\/inspiracion\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/chafiras.com\/inspiracion\/#organization\",\"name\":\"Las Chafiras, S.A.\",\"url\":\"https:\/\/chafiras.com\/inspiracion\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/chafiras.com\/inspiracion\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/chafiras.com\/inspiracion\/wp-content\/uploads\/2020\/02\/LOGO-CHAFIRAS_CORRECTO.png\",\"contentUrl\":\"https:\/\/chafiras.com\/inspiracion\/wp-content\/uploads\/2020\/02\/LOGO-CHAFIRAS_CORRECTO.png\",\"width\":774,\"height\":250,\"caption\":\"Las Chafiras, S.A.\"},\"image\":{\"@id\":\"https:\/\/chafiras.com\/inspiracion\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/chafirasoficial\/\",\"https:\/\/www.instagram.com\/chafirasoficial\/\",\"https:\/\/www.linkedin.com\/company\/chafirasoficial\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ideas para revestimiento de suelos y paredes: losas, azulejos,...","description":"\u00bfC\u00f3mo elegir suelos o azulejos para la pared del hogar? Consejos, ideas, estilos, tendencias,\u2026 Cambia el revestimiento del piso y las paredes \u00a1tu sue\u00f1o aqu\u00ed!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/chafiras.com\/inspiracion\/sobre\/decoracion\/ceramica\/","og_locale":"es_ES","og_type":"article","og_title":"Ideas para revestimiento de suelos y paredes: losas, azulejos,...","og_description":"\u00bfC\u00f3mo elegir suelos o azulejos para la pared del hogar? Consejos, ideas, estilos, tendencias,\u2026 Cambia el revestimiento del piso y las paredes \u00a1tu sue\u00f1o aqu\u00ed!","og_url":"https:\/\/chafiras.com\/inspiracion\/sobre\/decoracion\/ceramica\/","og_site_name":"Inspiraci\u00f3n para llevarte nuestra experiencia a casa","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/chafiras.com\/inspiracion\/sobre\/decoracion\/ceramica\/","url":"https:\/\/chafiras.com\/inspiracion\/sobre\/decoracion\/ceramica\/","name":"Ideas para revestimiento de suelos y paredes: losas, azulejos,...","isPartOf":{"@id":"https:\/\/chafiras.com\/inspiracion\/#website"},"description":"\u00bfC\u00f3mo elegir suelos o azulejos para la pared del hogar? Consejos, ideas, estilos, tendencias,\u2026 Cambia el revestimiento del piso y las paredes \u00a1tu sue\u00f1o aqu\u00ed!","breadcrumb":{"@id":"https:\/\/chafiras.com\/inspiracion\/sobre\/decoracion\/ceramica\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/chafiras.com\/inspiracion\/sobre\/decoracion\/ceramica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Chafiras","item":"https:\/\/chafiras.com\/inspiracion\/"},{"@type":"ListItem","position":2,"name":"Decoraci\u00f3n","item":"https:\/\/chafiras.com\/inspiracion\/sobre\/decoracion\/"},{"@type":"ListItem","position":3,"name":"Cer\u00e1mica"}]},{"@type":"WebSite","@id":"https:\/\/chafiras.com\/inspiracion\/#website","url":"https:\/\/chafiras.com\/inspiracion\/","name":"Inspiraci\u00f3n para llevarte nuestra experiencia a casa","description":"Herramientas para tu d\u00eda a d\u00eda","publisher":{"@id":"https:\/\/chafiras.com\/inspiracion\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/chafiras.com\/inspiracion\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/chafiras.com\/inspiracion\/#organization","name":"Las Chafiras, S.A.","url":"https:\/\/chafiras.com\/inspiracion\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/chafiras.com\/inspiracion\/#\/schema\/logo\/image\/","url":"https:\/\/chafiras.com\/inspiracion\/wp-content\/uploads\/2020\/02\/LOGO-CHAFIRAS_CORRECTO.png","contentUrl":"https:\/\/chafiras.com\/inspiracion\/wp-content\/uploads\/2020\/02\/LOGO-CHAFIRAS_CORRECTO.png","width":774,"height":250,"caption":"Las Chafiras, S.A."},"image":{"@id":"https:\/\/chafiras.com\/inspiracion\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/chafirasoficial\/","https:\/\/www.instagram.com\/chafirasoficial\/","https:\/\/www.linkedin.com\/company\/chafirasoficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/chafiras.com\/inspiracion\/wp-json\/wp\/v2\/categories\/9"}],"collection":[{"href":"https:\/\/chafiras.com\/inspiracion\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/chafiras.com\/inspiracion\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/chafiras.com\/inspiracion\/wp-json\/wp\/v2\/categories\/1"}],"wp:post_type":[{"href":"https:\/\/chafiras.com\/inspiracion\/wp-json\/wp\/v2\/posts?categories=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}